{"id":437,"date":"2024-03-18T12:31:21","date_gmt":"2024-03-18T16:31:21","guid":{"rendered":"https:\/\/mouvement.devrouge.com\/?post_type=elu&#038;p=437"},"modified":"2024-06-11T10:30:00","modified_gmt":"2024-06-11T14:30:00","slug":"sandra-desmeules","status":"publish","type":"elu","link":"https:\/\/mouvementlavallois.org\/en\/elu\/sandra-desmeules\/","title":{"rendered":"Sandra Desmeules"},"content":{"rendered":"<p class=\"p1\">Sandra Desmeules has been Councillor of Concorde\u2013Bois-de-Boulogne since 2013. In this capacity, she has been in charge of crucial issues as a member of the City of Laval\u2019s Executive Committee, including public safety, and is in charge of the Police Department, Fire Safety, Civil Security and Emergency Measures.<\/p>\n<p class=\"p1\">Ms. Desmeules proudly represents the City on the boards of Urgences-sant\u00e9, the Federation of Canadian Municipalities and the Office municipal d\u2019habitation de Laval.<\/p>\n<p class=\"p1\">With a master\u2019s degree from UQ\u00c0M\u2019s School of Management and as a member of the Ordre des conseillers en ressources humaines agr\u00e9\u00e9s (CRHA), she combines academic expertise with experience.<\/p>\n<p class=\"p1\">In seeking a new mandate, Ms. Desmeules remains true to her initial objective: to be an elected official who listens to her citizens and local organizations, investing all her energy in making a real difference in their lives.<\/p>\n","protected":false},"featured_media":1198,"template":"","class_list":["post-437","elu","type-elu","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sandra Desmeules | Mouvement Lavallois<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mouvementlavallois.org\/en\/elu\/sandra-desmeules\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sandra Desmeules | Mouvement Lavallois\" \/>\n<meta property=\"og:description\" content=\"Sandra Desmeules has been Councillor of Concorde\u2013Bois-de-Boulogne since 2013. In this capacity, she has been in charge of crucial issues as a member of the City of Laval\u2019s Executive Committee, including public safety, and is in charge of the Police Department, Fire Safety, Civil Security and Emergency Measures. Ms. Desmeules proudly represents the City on [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mouvementlavallois.org\/en\/elu\/sandra-desmeules\/\" \/>\n<meta property=\"og:site_name\" content=\"Mouvement Lavallois\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-11T14:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mouvementlavallois.org\/wp-content\/uploads\/2024\/03\/D-19816_Elus_0000s_0005_Sandra-Desmeules.png\" \/>\n\t<meta property=\"og:image:width\" content=\"359\" \/>\n\t<meta property=\"og:image:height\" content=\"581\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mouvementlavallois.org\\\/en\\\/elu\\\/sandra-desmeules\\\/\",\"url\":\"https:\\\/\\\/mouvementlavallois.org\\\/en\\\/elu\\\/sandra-desmeules\\\/\",\"name\":\"Sandra Desmeules | Mouvement Lavallois\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mouvementlavallois.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mouvementlavallois.org\\\/en\\\/elu\\\/sandra-desmeules\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mouvementlavallois.org\\\/en\\\/elu\\\/sandra-desmeules\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mouvementlavallois.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/12-1.png\",\"datePublished\":\"2024-03-18T16:31:21+00:00\",\"dateModified\":\"2024-06-11T14:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mouvementlavallois.org\\\/en\\\/elu\\\/sandra-desmeules\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mouvementlavallois.org\\\/en\\\/elu\\\/sandra-desmeules\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mouvementlavallois.org\\\/en\\\/elu\\\/sandra-desmeules\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mouvementlavallois.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/12-1.png\",\"contentUrl\":\"https:\\\/\\\/mouvementlavallois.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/12-1.png\",\"width\":2000,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mouvementlavallois.org\\\/en\\\/elu\\\/sandra-desmeules\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/mouvementlavallois.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sandra Desmeules\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mouvementlavallois.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mouvementlavallois.org\\\/en\\\/\",\"name\":\"Mouvement Lavallois\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mouvementlavallois.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sandra Desmeules | Mouvement Lavallois","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mouvementlavallois.org\/en\/elu\/sandra-desmeules\/","og_locale":"en_US","og_type":"article","og_title":"Sandra Desmeules | Mouvement Lavallois","og_description":"Sandra Desmeules has been Councillor of Concorde\u2013Bois-de-Boulogne since 2013. In this capacity, she has been in charge of crucial issues as a member of the City of Laval\u2019s Executive Committee, including public safety, and is in charge of the Police Department, Fire Safety, Civil Security and Emergency Measures. Ms. Desmeules proudly represents the City on [&hellip;]","og_url":"https:\/\/mouvementlavallois.org\/en\/elu\/sandra-desmeules\/","og_site_name":"Mouvement Lavallois","article_modified_time":"2024-06-11T14:30:00+00:00","og_image":[{"width":359,"height":581,"url":"https:\/\/mouvementlavallois.org\/wp-content\/uploads\/2024\/03\/D-19816_Elus_0000s_0005_Sandra-Desmeules.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mouvementlavallois.org\/en\/elu\/sandra-desmeules\/","url":"https:\/\/mouvementlavallois.org\/en\/elu\/sandra-desmeules\/","name":"Sandra Desmeules | Mouvement Lavallois","isPartOf":{"@id":"https:\/\/mouvementlavallois.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mouvementlavallois.org\/en\/elu\/sandra-desmeules\/#primaryimage"},"image":{"@id":"https:\/\/mouvementlavallois.org\/en\/elu\/sandra-desmeules\/#primaryimage"},"thumbnailUrl":"https:\/\/mouvementlavallois.org\/wp-content\/uploads\/2025\/04\/12-1.png","datePublished":"2024-03-18T16:31:21+00:00","dateModified":"2024-06-11T14:30:00+00:00","breadcrumb":{"@id":"https:\/\/mouvementlavallois.org\/en\/elu\/sandra-desmeules\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mouvementlavallois.org\/en\/elu\/sandra-desmeules\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mouvementlavallois.org\/en\/elu\/sandra-desmeules\/#primaryimage","url":"https:\/\/mouvementlavallois.org\/wp-content\/uploads\/2025\/04\/12-1.png","contentUrl":"https:\/\/mouvementlavallois.org\/wp-content\/uploads\/2025\/04\/12-1.png","width":2000,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/mouvementlavallois.org\/en\/elu\/sandra-desmeules\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/mouvementlavallois.org\/en\/"},{"@type":"ListItem","position":2,"name":"Sandra Desmeules"}]},{"@type":"WebSite","@id":"https:\/\/mouvementlavallois.org\/en\/#website","url":"https:\/\/mouvementlavallois.org\/en\/","name":"Mouvement Lavallois","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mouvementlavallois.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/mouvementlavallois.org\/en\/wp-json\/wp\/v2\/elu\/437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mouvementlavallois.org\/en\/wp-json\/wp\/v2\/elu"}],"about":[{"href":"https:\/\/mouvementlavallois.org\/en\/wp-json\/wp\/v2\/types\/elu"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mouvementlavallois.org\/en\/wp-json\/wp\/v2\/media\/1198"}],"wp:attachment":[{"href":"https:\/\/mouvementlavallois.org\/en\/wp-json\/wp\/v2\/media?parent=437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}